{"id":4414,"date":"2021-06-22T12:34:46","date_gmt":"2021-06-22T19:34:46","guid":{"rendered":"https:\/\/mothertobaby.org\/baby-blog\/cual-es-lo-ultimo-acerca-del-cuidado-de-la-piel\/"},"modified":"2021-06-22T12:34:55","modified_gmt":"2021-06-22T19:34:55","slug":"cual-es-lo-ultimo-acerca-del-cuidado-de-la-piel","status":"publish","type":"post","link":"https:\/\/mothertobaby.org\/es\/baby-blog\/cual-es-lo-ultimo-acerca-del-cuidado-de-la-piel\/","title":{"rendered":"\u00bfCu\u00e1l es lo \u00faltimo acerca del cuidado de la piel?"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u201cCu\u00e1les productos puedo usar en la piel durante el embarazo y la lactancia?\u201d Como especialista en informaci\u00f3n de MotherToBaby respondiendo a trav\u00e9s de nuestro servicio de mensajes de texto, \u00a1todos los d\u00edas recibo preguntas sobre todo tipo de producto que se le ocurra que se pueda aplicar en la piel! Cualquier cosa, desde cremas para picaz\u00f3n, cremas antibi\u00f3ticas, productos con vitamina C, aceites esenciales, cremas y geles homeop\u00e1ticos, y productos para el acn\u00e9, hasta cosm\u00e9ticos y productos para el cuidado general de la piel. El embarazo y la lactancia pueden ser momentos estresantes, y como siempre queremos lo mejor para nuestros beb\u00e9s, a todas nos preocupa que un producto que estamos usando en la piel pueda llegar al beb\u00e9 y ser un problema. Pero, \u00bfes cierto que pueda causar alg\u00fan problema? \u00bfDe qu\u00e9 deber\u00e1 preocuparse y qu\u00e9 puede usar (seg\u00fan las indicaciones) sin preocupaciones?<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-your-skin\">Su piel<\/h2>\n\n<p class=\"wp-block-paragraph\">Primero, hablemos sobre la piel y c\u00f3mo los productos t\u00f3picos (cosas que se aplican en la piel) entran en su organismo. La piel es un tejido vivo grande y din\u00e1mico que se compone de diferentes capas. Necesitamos entender el proceso de absorci\u00f3n para evaluar la seguridad de los productos cosm\u00e9ticos, medicinales, y qu\u00edmicos que entran en contacto con nuestra piel. Cuando se pone una sustancia en la piel, la sustancia tiene que pasar primero a trav\u00e9s de la capa externa de la piel llamada estrato c\u00f3rneo, que se compone de c\u00e9lulas muertas. Luego vienen las capas vivas de nuestra piel, la epidermis (barrera impermeable), la dermis (tejido conectivo, fol\u00edculos pilosos, y gl\u00e1ndulas sudor\u00edparas), la hipodermis (grasa y tejido conectivo) y la red vascular. <\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-how-much-is-absorbed\">\u00bfCu\u00e1nto se absorbe?<\/h3>\n\n<p class=\"wp-block-paragraph\">Diferentes factores afectan la absorci\u00f3n de la piel, como la cantidad que se aplica, el estado f\u00edsico del producto (es un l\u00edquido, polvo, gel, etc.), d\u00f3nde se aplica en el cuerpo, qu\u00e9 tan grande es el \u00e1rea donde se aplica, la edad de la persona, y si la piel est\u00e1 h\u00fameda o seca en el momento de la aplicaci\u00f3n. A menudo, s\u00f3lo el 1 o 2% de una dosis aplicada es absorbida por el organismo. Pero a veces, se absorbe m\u00e1s, especialmente si la piel tiene heridas abiertas, grietas, etc. o si tiene una condici\u00f3n de la piel como eczema. De hecho, qu\u00e9 tan \u00abcompleta\u00bb est\u00e1 su piel puede ser el factor m\u00e1s importante para determinar qu\u00e9 tan efectiva puede ser una barrera para los productos t\u00f3picos.<\/p>\n\n<p class=\"wp-block-paragraph\">Puede ser dif\u00edcil obtener buena informaci\u00f3n de seguridad sobre cada tipo de producto t\u00f3pico. La Administraci\u00f3n de Alimentos y Medicamentos (FDA, por sus siglas en ingl\u00e9s) requiere que los productos cosm\u00e9ticos sean \u00abseguros,\u00bb lo que se basa en su etiquetado y uso espec\u00edficos. Sin embargo, los productos cosm\u00e9ticos no necesitan la aprobaci\u00f3n de la FDA para ser vendidos en el mercado, y a menudo las empresas hacen afirmaciones que no han sido estudiadas y no se pueden demostrar. Por lo tanto, siempre es una buena idea consultar con nuestros especialistas en informaci\u00f3n de MotherToBaby y dejarnos investigar el producto y sus ingredientes para usted.<\/p>\n\n<p class=\"wp-block-paragraph\">Muchas veces durante el embarazo y la lactancia, las personas se preocupan por el uso de los <a href=\"https:\/\/mothertobaby.org\/es\/hojas-informativas\/la-isotretinoina-accutane\/\">retinoides<\/a> (una clase de compuestos qu\u00edmicos contenidos en los tratamientos para el acn\u00e9, la psoriasis, las arrugas, y otras condiciones de la piel), <a href=\"https:\/\/mothertobaby.org\/es\/hojas-informativas\/tratamientos-topicos-para-el-acne\/\">dosis altas de \u00e1cido salic\u00edlico<\/a> (un ingrediente com\u00fan en los tratamientos t\u00f3picos para el acn\u00e9), <a href=\"https:\/\/mothertobaby.org\/es\/hojas-informativas\/trabajar-en-salon-de-unas\/\">formaldeh\u00eddo<\/a> (a menudo se usa como conservante en productos cosm\u00e9ticos), hidroquinona (un agente para aclarar la piel que se puede usar para tratar las manchas de la edad y las manchas solares), y <a href=\"https:\/\/mothertobaby.org\/es\/baby-blog\/escrudinando-el-bloqueador-solar-durante-el-embarazo\/\">bloqueadores solares<\/a> qu\u00edmicos, por nombrar algunos. Estos productos pueden presentar algunos problemas y deben usarse con precauci\u00f3n durante el embarazo y la lactancia.<\/p>\n\n<p class=\"wp-block-paragraph\">Otros productos que se aplican a la piel son menos preocupantes en la mayor\u00eda de los casos. Estos incluyen cremas antibi\u00f3ticas de venta libre, <a href=\"https:\/\/mothertobaby.org\/es\/hojas-informativas\/los-corticosteroides-topicos-el-embarazo\/\">cremas con corticosteroides<\/a> (utilizadas para reducir la inflamaci\u00f3n de la piel y la irritaci\u00f3n por piquetes de insectos o roble\/hiedra venenoso, pero tambi\u00e9n en tratamientos para el eczema y la psoriasis), <a href=\"https:\/\/mothertobaby.org\/podcast\/episode-1-are-essential-oils-safe-while-pregnant-or-breastfeeding\/\">aceites esenciales<\/a>, productos tipo mentol y lidoca\u00edna (utilizados para enfriar o adormecer la piel), per\u00f3xido de hidr\u00f3geno (utilizado en tratamientos para el acn\u00e9, las manchas solares, y las manchas de la edad), productos de fl\u00faor y <a href=\"https:\/\/mothertobaby.org\/es\/baby-blog\/no-lo-pelees-con-unas-y-dientes-el-dentista-esta-contigo-durante-el-embarazo\/\">dentales<\/a>, cremas y geles homeop\u00e1ticos, productos con <a href=\"https:\/\/mothertobaby.org\/es\/hojas-informativas\/vitamin-c\/\">vitamina C<\/a> (utilizados en tratamientos para reducir las l\u00edneas de expresi\u00f3n y como antioxidante para proteger la piel), y cosas que se ponen en el <a href=\"https:\/\/mothertobaby.org\/es\/hojas-informativas\/tratamientos-para-el-cabello\/\">cabello<\/a> y las <a href=\"https:\/\/mothertobaby.org\/es\/baby-blog\/productos-para-unas-durante-el-embarazo\/\">u\u00f1as<\/a>.<\/p>\n\n<p class=\"wp-block-paragraph\">\u00a1As\u00ed que ese es lo \u00faltimo acerca del cuidado de la piel! Es posible que pueda usar m\u00e1s productos en su piel de lo que pensaba durante el embarazo y la lactancia. Incluso con un producto que se considera de bajo riesgo, es posible que desee consultar con su proveedor de salud o con nosotros si tiene alguna inquietud antes de usarlo. Tenemos una serie de <a href=\"https:\/\/mothertobaby.org\/es\/hojas-informativas\/\">hojas informativas<\/a> y <a href=\"https:\/\/mothertobaby.org\/es\/blog-del-bebe\/\">blogs<\/a> que pueden responder a algunas de sus preguntas sobre los productos t\u00f3picos, y nuestros especialistas en informaci\u00f3n siempre estamos encantados de responder a sus preguntas por tel\u00e9fono, texto, <a href=\"https:\/\/mothertobaby.org\/ask-an-expert\/\">correo electr\u00f3nico<\/a> o chat.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cCu\u00e1les productos puedo usar en la piel durante el embarazo y la lactancia?\u201d Como especialista en informaci\u00f3n de MotherToBaby respondiendo a trav\u00e9s de nuestro servicio de mensajes de texto, \u00a1todos los d\u00edas recibo preguntas sobre todo tipo de producto que se le ocurra que se pueda aplicar en la piel! Cualquier cosa, desde cremas para [&hellip;]<\/p>\n","protected":false},"author":117,"featured_media":1144,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_searchwp_excluded":"","_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"categories":[241],"tags":[895,894],"related-content":[615,580,600],"class_list":["post-4414","post","type-post","status-publish","format-standard","has-post-thumbnail","category-tratamientos-cosmeticos","tag-cremas-topicas","tag-proteccion-de-la-piel","related-content-aceites-esenciales","related-content-eczema-2","related-content-tratamientos-cosmeticos","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u00bfCu\u00e1l es lo \u00faltimo acerca del cuidado de la piel? - MotherToBaby<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mothertobaby.org\/es\/baby-blog\/cual-es-lo-ultimo-acerca-del-cuidado-de-la-piel\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfCu\u00e1l es lo \u00faltimo acerca del cuidado de la piel?\" \/>\n<meta property=\"og:description\" content=\"\u201cCu\u00e1les productos puedo usar en la piel durante el embarazo y la lactancia?\u201d Como especialista en informaci\u00f3n de MotherToBaby respondiendo a trav\u00e9s de nuestro servicio de mensajes de texto, \u00a1todos los d\u00edas recibo preguntas sobre todo tipo de producto que se le ocurra que se pueda aplicar en la piel! Cualquier cosa, desde cremas para [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mothertobaby.org\/es\/baby-blog\/cual-es-lo-ultimo-acerca-del-cuidado-de-la-piel\/\" \/>\n<meta property=\"og:site_name\" content=\"MotherToBaby\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-22T19:34:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-22T19:34:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mothertobaby.org\/wp-content\/uploads\/2020\/04\/blog-hero-fpo-v1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"816\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Lori Wolfe, CGC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lori Wolfe, CGC\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mothertobaby.org\\\/es\\\/baby-blog\\\/cual-es-lo-ultimo-acerca-del-cuidado-de-la-piel\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mothertobaby.org\\\/es\\\/baby-blog\\\/cual-es-lo-ultimo-acerca-del-cuidado-de-la-piel\\\/\"},\"author\":{\"name\":\"Lori Wolfe, CGC\",\"@id\":\"https:\\\/\\\/mothertobaby.org\\\/es\\\/#\\\/schema\\\/person\\\/eded50cd0d39885454bb655313965d05\"},\"headline\":\"\u00bfCu\u00e1l es lo \u00faltimo acerca del cuidado de la piel?\",\"datePublished\":\"2021-06-22T19:34:46+00:00\",\"dateModified\":\"2021-06-22T19:34:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mothertobaby.org\\\/es\\\/baby-blog\\\/cual-es-lo-ultimo-acerca-del-cuidado-de-la-piel\\\/\"},\"wordCount\":924,\"publisher\":{\"@id\":\"https:\\\/\\\/mothertobaby.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/mothertobaby.org\\\/es\\\/baby-blog\\\/cual-es-lo-ultimo-acerca-del-cuidado-de-la-piel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mothertobaby.org\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/blog-hero-fpo-v1-scaled.jpg\",\"keywords\":[\"cremas t\u00f3picas\",\"protecci\u00f3n de la piel\"],\"articleSection\":[\"Tratamientos Cosm\u00e9ticos\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mothertobaby.org\\\/es\\\/baby-blog\\\/cual-es-lo-ultimo-acerca-del-cuidado-de-la-piel\\\/\",\"url\":\"https:\\\/\\\/mothertobaby.org\\\/es\\\/baby-blog\\\/cual-es-lo-ultimo-acerca-del-cuidado-de-la-piel\\\/\",\"name\":\"\u00bfCu\u00e1l es lo \u00faltimo acerca del cuidado de la piel? - MotherToBaby\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mothertobaby.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mothertobaby.org\\\/es\\\/baby-blog\\\/cual-es-lo-ultimo-acerca-del-cuidado-de-la-piel\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mothertobaby.org\\\/es\\\/baby-blog\\\/cual-es-lo-ultimo-acerca-del-cuidado-de-la-piel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mothertobaby.org\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/blog-hero-fpo-v1-scaled.jpg\",\"datePublished\":\"2021-06-22T19:34:46+00:00\",\"dateModified\":\"2021-06-22T19:34:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mothertobaby.org\\\/es\\\/baby-blog\\\/cual-es-lo-ultimo-acerca-del-cuidado-de-la-piel\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mothertobaby.org\\\/es\\\/baby-blog\\\/cual-es-lo-ultimo-acerca-del-cuidado-de-la-piel\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/mothertobaby.org\\\/es\\\/baby-blog\\\/cual-es-lo-ultimo-acerca-del-cuidado-de-la-piel\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mothertobaby.org\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/blog-hero-fpo-v1-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/mothertobaby.org\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/blog-hero-fpo-v1-scaled.jpg\",\"width\":2560,\"height\":816},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mothertobaby.org\\\/es\\\/baby-blog\\\/cual-es-lo-ultimo-acerca-del-cuidado-de-la-piel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mothertobaby.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfCu\u00e1l es lo \u00faltimo acerca del cuidado de la piel?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mothertobaby.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/mothertobaby.org\\\/es\\\/\",\"name\":\"MotherToBaby\",\"description\":\"Medications and More during pregnancy and breastfeeding\",\"publisher\":{\"@id\":\"https:\\\/\\\/mothertobaby.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mothertobaby.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mothertobaby.org\\\/es\\\/#organization\",\"name\":\"MotherToBaby\",\"url\":\"https:\\\/\\\/mothertobaby.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/mothertobaby.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mothertobaby.org\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/MTB-horz-copyright-sm-1.png\",\"contentUrl\":\"https:\\\/\\\/mothertobaby.org\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/MTB-horz-copyright-sm-1.png\",\"width\":284,\"height\":52,\"caption\":\"MotherToBaby\"},\"image\":{\"@id\":\"https:\\\/\\\/mothertobaby.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mothertobaby.org\\\/es\\\/#\\\/schema\\\/person\\\/eded50cd0d39885454bb655313965d05\",\"name\":\"Lori Wolfe, CGC\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/mothertobaby.org\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/MotherToBaby-Lori-Wolfe-400x350-07.20-150x150.jpg\",\"url\":\"https:\\\/\\\/mothertobaby.org\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/MotherToBaby-Lori-Wolfe-400x350-07.20-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/mothertobaby.org\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/MotherToBaby-Lori-Wolfe-400x350-07.20-150x150.jpg\",\"caption\":\"Lori Wolfe, CGC\"},\"description\":\"is a board certified Genetic Counselor and the Director of MotherToBaby\u2019s North Texas affiliate. MotherToBaby aims to educate women about medications and more during pregnancy and breastfeeding. Along with answering women\u2019s and health professionals\u2019 questions regarding exposures during pregnancy\\\/breastfeeding via MotherToBaby\u2019s toll-free number, text line and by email, Wolfe also teaches at the University of North Texas, provides educational talks regarding pregnancy health in community clinics and high schools.\",\"url\":\"https:\\\/\\\/mothertobaby.org\\\/es\\\/baby-blog\\\/author\\\/lwolfe\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u00bfCu\u00e1l es lo \u00faltimo acerca del cuidado de la piel? - MotherToBaby","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mothertobaby.org\/es\/baby-blog\/cual-es-lo-ultimo-acerca-del-cuidado-de-la-piel\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfCu\u00e1l es lo \u00faltimo acerca del cuidado de la piel?","og_description":"\u201cCu\u00e1les productos puedo usar en la piel durante el embarazo y la lactancia?\u201d Como especialista en informaci\u00f3n de MotherToBaby respondiendo a trav\u00e9s de nuestro servicio de mensajes de texto, \u00a1todos los d\u00edas recibo preguntas sobre todo tipo de producto que se le ocurra que se pueda aplicar en la piel! Cualquier cosa, desde cremas para [&hellip;]","og_url":"https:\/\/mothertobaby.org\/es\/baby-blog\/cual-es-lo-ultimo-acerca-del-cuidado-de-la-piel\/","og_site_name":"MotherToBaby","article_published_time":"2021-06-22T19:34:46+00:00","article_modified_time":"2021-06-22T19:34:55+00:00","og_image":[{"width":2560,"height":816,"url":"https:\/\/mothertobaby.org\/wp-content\/uploads\/2020\/04\/blog-hero-fpo-v1-scaled.jpg","type":"image\/jpeg"}],"author":"Lori Wolfe, CGC","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Lori Wolfe, CGC","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mothertobaby.org\/es\/baby-blog\/cual-es-lo-ultimo-acerca-del-cuidado-de-la-piel\/#article","isPartOf":{"@id":"https:\/\/mothertobaby.org\/es\/baby-blog\/cual-es-lo-ultimo-acerca-del-cuidado-de-la-piel\/"},"author":{"name":"Lori Wolfe, CGC","@id":"https:\/\/mothertobaby.org\/es\/#\/schema\/person\/eded50cd0d39885454bb655313965d05"},"headline":"\u00bfCu\u00e1l es lo \u00faltimo acerca del cuidado de la piel?","datePublished":"2021-06-22T19:34:46+00:00","dateModified":"2021-06-22T19:34:55+00:00","mainEntityOfPage":{"@id":"https:\/\/mothertobaby.org\/es\/baby-blog\/cual-es-lo-ultimo-acerca-del-cuidado-de-la-piel\/"},"wordCount":924,"publisher":{"@id":"https:\/\/mothertobaby.org\/es\/#organization"},"image":{"@id":"https:\/\/mothertobaby.org\/es\/baby-blog\/cual-es-lo-ultimo-acerca-del-cuidado-de-la-piel\/#primaryimage"},"thumbnailUrl":"https:\/\/mothertobaby.org\/wp-content\/uploads\/2020\/04\/blog-hero-fpo-v1-scaled.jpg","keywords":["cremas t\u00f3picas","protecci\u00f3n de la piel"],"articleSection":["Tratamientos Cosm\u00e9ticos"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/mothertobaby.org\/es\/baby-blog\/cual-es-lo-ultimo-acerca-del-cuidado-de-la-piel\/","url":"https:\/\/mothertobaby.org\/es\/baby-blog\/cual-es-lo-ultimo-acerca-del-cuidado-de-la-piel\/","name":"\u00bfCu\u00e1l es lo \u00faltimo acerca del cuidado de la piel? - MotherToBaby","isPartOf":{"@id":"https:\/\/mothertobaby.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mothertobaby.org\/es\/baby-blog\/cual-es-lo-ultimo-acerca-del-cuidado-de-la-piel\/#primaryimage"},"image":{"@id":"https:\/\/mothertobaby.org\/es\/baby-blog\/cual-es-lo-ultimo-acerca-del-cuidado-de-la-piel\/#primaryimage"},"thumbnailUrl":"https:\/\/mothertobaby.org\/wp-content\/uploads\/2020\/04\/blog-hero-fpo-v1-scaled.jpg","datePublished":"2021-06-22T19:34:46+00:00","dateModified":"2021-06-22T19:34:55+00:00","breadcrumb":{"@id":"https:\/\/mothertobaby.org\/es\/baby-blog\/cual-es-lo-ultimo-acerca-del-cuidado-de-la-piel\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mothertobaby.org\/es\/baby-blog\/cual-es-lo-ultimo-acerca-del-cuidado-de-la-piel\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/mothertobaby.org\/es\/baby-blog\/cual-es-lo-ultimo-acerca-del-cuidado-de-la-piel\/#primaryimage","url":"https:\/\/mothertobaby.org\/wp-content\/uploads\/2020\/04\/blog-hero-fpo-v1-scaled.jpg","contentUrl":"https:\/\/mothertobaby.org\/wp-content\/uploads\/2020\/04\/blog-hero-fpo-v1-scaled.jpg","width":2560,"height":816},{"@type":"BreadcrumbList","@id":"https:\/\/mothertobaby.org\/es\/baby-blog\/cual-es-lo-ultimo-acerca-del-cuidado-de-la-piel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mothertobaby.org\/es\/"},{"@type":"ListItem","position":2,"name":"\u00bfCu\u00e1l es lo \u00faltimo acerca del cuidado de la piel?"}]},{"@type":"WebSite","@id":"https:\/\/mothertobaby.org\/es\/#website","url":"https:\/\/mothertobaby.org\/es\/","name":"MotherToBaby","description":"Medications and More during pregnancy and breastfeeding","publisher":{"@id":"https:\/\/mothertobaby.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mothertobaby.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/mothertobaby.org\/es\/#organization","name":"MotherToBaby","url":"https:\/\/mothertobaby.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/mothertobaby.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/mothertobaby.org\/wp-content\/uploads\/2023\/06\/MTB-horz-copyright-sm-1.png","contentUrl":"https:\/\/mothertobaby.org\/wp-content\/uploads\/2023\/06\/MTB-horz-copyright-sm-1.png","width":284,"height":52,"caption":"MotherToBaby"},"image":{"@id":"https:\/\/mothertobaby.org\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/mothertobaby.org\/es\/#\/schema\/person\/eded50cd0d39885454bb655313965d05","name":"Lori Wolfe, CGC","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/mothertobaby.org\/wp-content\/uploads\/2020\/07\/MotherToBaby-Lori-Wolfe-400x350-07.20-150x150.jpg","url":"https:\/\/mothertobaby.org\/wp-content\/uploads\/2020\/07\/MotherToBaby-Lori-Wolfe-400x350-07.20-150x150.jpg","contentUrl":"https:\/\/mothertobaby.org\/wp-content\/uploads\/2020\/07\/MotherToBaby-Lori-Wolfe-400x350-07.20-150x150.jpg","caption":"Lori Wolfe, CGC"},"description":"is a board certified Genetic Counselor and the Director of MotherToBaby\u2019s North Texas affiliate. MotherToBaby aims to educate women about medications and more during pregnancy and breastfeeding. Along with answering women\u2019s and health professionals\u2019 questions regarding exposures during pregnancy\/breastfeeding via MotherToBaby\u2019s toll-free number, text line and by email, Wolfe also teaches at the University of North Texas, provides educational talks regarding pregnancy health in community clinics and high schools.","url":"https:\/\/mothertobaby.org\/es\/baby-blog\/author\/lwolfe\/"}]}},"featured_image_src":"https:\/\/mothertobaby.org\/wp-content\/uploads\/2020\/04\/blog-hero-fpo-v1-scaled.jpg","featured_image_src_square":"https:\/\/mothertobaby.org\/wp-content\/uploads\/2020\/04\/blog-hero-fpo-v1-scaled.jpg","author_info":{"display_name":"Lori Wolfe, CGC","author_link":"https:\/\/mothertobaby.org\/es\/baby-blog\/author\/lwolfe\/"},"_links":{"self":[{"href":"https:\/\/mothertobaby.org\/es\/wp-json\/wp\/v2\/posts\/4414","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mothertobaby.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mothertobaby.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mothertobaby.org\/es\/wp-json\/wp\/v2\/users\/117"}],"replies":[{"embeddable":true,"href":"https:\/\/mothertobaby.org\/es\/wp-json\/wp\/v2\/comments?post=4414"}],"version-history":[{"count":0,"href":"https:\/\/mothertobaby.org\/es\/wp-json\/wp\/v2\/posts\/4414\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mothertobaby.org\/es\/wp-json\/wp\/v2\/media\/1144"}],"wp:attachment":[{"href":"https:\/\/mothertobaby.org\/es\/wp-json\/wp\/v2\/media?parent=4414"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mothertobaby.org\/es\/wp-json\/wp\/v2\/categories?post=4414"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mothertobaby.org\/es\/wp-json\/wp\/v2\/tags?post=4414"},{"taxonomy":"related-content","embeddable":true,"href":"https:\/\/mothertobaby.org\/es\/wp-json\/wp\/v2\/related-content?post=4414"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}